{"id":30,"date":"2023-03-27T14:30:38","date_gmt":"2023-03-27T07:30:38","guid":{"rendered":"http:\/\/localhost:4000\/home?page_id=30"},"modified":"2024-04-11T13:49:30","modified_gmt":"2024-04-11T06:49:30","slug":"cloud","status":"publish","type":"page","link":"https:\/\/www.skyfrog.net\/home\/en\/cloud\/","title":{"rendered":"Cloud Service"},"content":{"rendered":"<style>.elementor-30 .elementor-element.elementor-element-21794b7{margin-top:50px;margin-bottom:50px;}.elementor-30 .elementor-element.elementor-element-23836b5 > .elementor-element-populated{margin:0px 20px 0px 0px;--e-column-margin-right:20px;--e-column-margin-left:0px;}.elementor-widget-image .widget-image-caption{color:var( --e-global-color-text );font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-weight:var( --e-global-typography-text-font-weight );}.elementor-widget-heading .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );color:var( --e-global-color-primary );}.elementor-30 .elementor-element.elementor-element-fa55c55 .elementor-heading-title{font-size:30px;font-weight:500;line-height:1.6em;color:#000000;}.elementor-30 .elementor-element.elementor-element-fa55c55 > .elementor-widget-container{margin:0px 0px 0px 0px;}.elementor-widget-text-editor{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-weight:var( --e-global-typography-text-font-weight );color:var( --e-global-color-text );}.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:var( --e-global-color-primary );}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap, .elementor-widget-text-editor.elementor-drop-cap-view-default .elementor-drop-cap{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-30 .elementor-element.elementor-element-6a1f43c{font-size:16px;font-weight:300;line-height:1.9em;color:#272727;}.elementor-30 .elementor-element.elementor-element-6a1f43c > .elementor-widget-container{margin:0px 0px 0px 0px;}.elementor-30 .elementor-element.elementor-element-d8cdb3f .elementor-heading-title{font-family:\"Kanit\", Sans-serif;font-size:30px;font-weight:500;}.elementor-30 .elementor-element.elementor-element-d64213d{font-family:\"Kanit\", Sans-serif;font-weight:300;}.elementor-30 .elementor-element.elementor-element-38dc8c8:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-30 .elementor-element.elementor-element-38dc8c8 > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#ffffff;}.elementor-30 .elementor-element.elementor-element-38dc8c8 > .elementor-element-populated, .elementor-30 .elementor-element.elementor-element-38dc8c8 > .elementor-element-populated > .elementor-background-overlay, .elementor-30 .elementor-element.elementor-element-38dc8c8 > .elementor-background-slideshow{border-radius:15px 15px 15px 70px;}.elementor-30 .elementor-element.elementor-element-38dc8c8 > .elementor-element-populated{box-shadow:0px 0px 20px 0px rgba(0,0,0,0.05);transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;margin:3% 3% 3% 3%;--e-column-margin-right:3%;--e-column-margin-left:3%;padding:14% 14% 14% 14%;}.elementor-30 .elementor-element.elementor-element-38dc8c8 > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-widget-image-box .elementor-image-box-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );color:var( --e-global-color-primary );}.elementor-widget-image-box:has(:hover) .elementor-image-box-title,\n\t\t\t\t\t .elementor-widget-image-box:has(:focus) .elementor-image-box-title{color:var( --e-global-color-primary );}.elementor-widget-image-box .elementor-image-box-description{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-weight:var( --e-global-typography-text-font-weight );color:var( --e-global-color-text );}.elementor-30 .elementor-element.elementor-element-08c5e95 .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-08c5e95.elementor-position-right .elementor-image-box-img{margin-left:15px;}.elementor-30 .elementor-element.elementor-element-08c5e95.elementor-position-left .elementor-image-box-img{margin-right:15px;}.elementor-30 .elementor-element.elementor-element-08c5e95.elementor-position-top .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-08c5e95 .elementor-image-box-wrapper .elementor-image-box-img{width:35%;}.elementor-30 .elementor-element.elementor-element-08c5e95 .elementor-image-box-img img{transition-duration:0.3s;}.elementor-30 .elementor-element.elementor-element-08c5e95 .elementor-image-box-title{font-family:\"Kanit\", Sans-serif;font-size:20px;font-weight:500;text-transform:capitalize;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-08c5e95 .elementor-image-box-description{font-family:\"Montserrat\", Sans-serif;font-size:16px;font-weight:300;line-height:1.4em;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-d7c01dd:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-30 .elementor-element.elementor-element-d7c01dd > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#ffffff;}.elementor-30 .elementor-element.elementor-element-d7c01dd > .elementor-element-populated, .elementor-30 .elementor-element.elementor-element-d7c01dd > .elementor-element-populated > .elementor-background-overlay, .elementor-30 .elementor-element.elementor-element-d7c01dd > .elementor-background-slideshow{border-radius:15px 15px 15px 70px;}.elementor-30 .elementor-element.elementor-element-d7c01dd > .elementor-element-populated{box-shadow:0px 0px 20px 0px rgba(0,0,0,0.05);transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;margin:3% 3% 3% 3%;--e-column-margin-right:3%;--e-column-margin-left:3%;padding:14% 14% 14% 14%;}.elementor-30 .elementor-element.elementor-element-d7c01dd > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-30 .elementor-element.elementor-element-1c5968b .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-1c5968b.elementor-position-right .elementor-image-box-img{margin-left:15px;}.elementor-30 .elementor-element.elementor-element-1c5968b.elementor-position-left .elementor-image-box-img{margin-right:15px;}.elementor-30 .elementor-element.elementor-element-1c5968b.elementor-position-top .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-1c5968b .elementor-image-box-wrapper .elementor-image-box-img{width:35%;}.elementor-30 .elementor-element.elementor-element-1c5968b .elementor-image-box-img img{transition-duration:0.3s;}.elementor-30 .elementor-element.elementor-element-1c5968b .elementor-image-box-title{font-family:\"Kanit\", Sans-serif;font-size:20px;font-weight:500;text-transform:capitalize;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-1c5968b .elementor-image-box-description{font-family:\"Montserrat\", Sans-serif;font-size:16px;font-weight:300;line-height:1.4em;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-950270f:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-30 .elementor-element.elementor-element-950270f > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#ffffff;}.elementor-30 .elementor-element.elementor-element-950270f > .elementor-element-populated, .elementor-30 .elementor-element.elementor-element-950270f > .elementor-element-populated > .elementor-background-overlay, .elementor-30 .elementor-element.elementor-element-950270f > .elementor-background-slideshow{border-radius:15px 15px 15px 70px;}.elementor-30 .elementor-element.elementor-element-950270f > .elementor-element-populated{box-shadow:0px 0px 20px 0px rgba(0,0,0,0.05);transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;margin:3% 3% 3% 3%;--e-column-margin-right:3%;--e-column-margin-left:3%;padding:14% 14% 14% 14%;}.elementor-30 .elementor-element.elementor-element-950270f > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-30 .elementor-element.elementor-element-e2d5fd0 .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-e2d5fd0.elementor-position-right .elementor-image-box-img{margin-left:15px;}.elementor-30 .elementor-element.elementor-element-e2d5fd0.elementor-position-left .elementor-image-box-img{margin-right:15px;}.elementor-30 .elementor-element.elementor-element-e2d5fd0.elementor-position-top .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-e2d5fd0 .elementor-image-box-wrapper .elementor-image-box-img{width:35%;}.elementor-30 .elementor-element.elementor-element-e2d5fd0 .elementor-image-box-img img{transition-duration:0.3s;}.elementor-30 .elementor-element.elementor-element-e2d5fd0 .elementor-image-box-title{font-family:\"Kanit\", Sans-serif;font-size:20px;font-weight:500;text-transform:capitalize;-webkit-text-stroke-color:#000;stroke:#000;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-e2d5fd0 .elementor-image-box-description{font-family:\"Montserrat\", Sans-serif;font-size:16px;font-weight:300;line-height:1.4em;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-7230a2a:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-30 .elementor-element.elementor-element-7230a2a > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#ffffff;}.elementor-30 .elementor-element.elementor-element-7230a2a > .elementor-element-populated, .elementor-30 .elementor-element.elementor-element-7230a2a > .elementor-element-populated > .elementor-background-overlay, .elementor-30 .elementor-element.elementor-element-7230a2a > .elementor-background-slideshow{border-radius:15px 15px 15px 70px;}.elementor-30 .elementor-element.elementor-element-7230a2a > .elementor-element-populated{box-shadow:0px 0px 20px 0px rgba(0,0,0,0.05);transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;margin:3% 3% 3% 3%;--e-column-margin-right:3%;--e-column-margin-left:3%;padding:14% 14% 14% 14%;}.elementor-30 .elementor-element.elementor-element-7230a2a > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-30 .elementor-element.elementor-element-aa25385 .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-aa25385.elementor-position-right .elementor-image-box-img{margin-left:15px;}.elementor-30 .elementor-element.elementor-element-aa25385.elementor-position-left .elementor-image-box-img{margin-right:15px;}.elementor-30 .elementor-element.elementor-element-aa25385.elementor-position-top .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-aa25385 .elementor-image-box-wrapper .elementor-image-box-img{width:35%;}.elementor-30 .elementor-element.elementor-element-aa25385 .elementor-image-box-img img{transition-duration:0.3s;}.elementor-30 .elementor-element.elementor-element-aa25385 .elementor-image-box-title{font-family:\"Kanit\", Sans-serif;font-size:20px;font-weight:500;text-transform:capitalize;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-aa25385 .elementor-image-box-description{font-family:\"Kanit\", Sans-serif;font-size:16px;font-weight:300;line-height:1.4em;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-4de4672:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-30 .elementor-element.elementor-element-4de4672 > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#ffffff;}.elementor-30 .elementor-element.elementor-element-4de4672 > .elementor-element-populated, .elementor-30 .elementor-element.elementor-element-4de4672 > .elementor-element-populated > .elementor-background-overlay, .elementor-30 .elementor-element.elementor-element-4de4672 > .elementor-background-slideshow{border-radius:15px 15px 15px 70px;}.elementor-30 .elementor-element.elementor-element-4de4672 > .elementor-element-populated{box-shadow:0px 0px 20px 0px rgba(0,0,0,0.05);transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;margin:3% 3% 3% 3%;--e-column-margin-right:3%;--e-column-margin-left:3%;padding:14% 14% 14% 14%;}.elementor-30 .elementor-element.elementor-element-4de4672 > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-30 .elementor-element.elementor-element-8f2fb4d .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-8f2fb4d.elementor-position-right .elementor-image-box-img{margin-left:15px;}.elementor-30 .elementor-element.elementor-element-8f2fb4d.elementor-position-left .elementor-image-box-img{margin-right:15px;}.elementor-30 .elementor-element.elementor-element-8f2fb4d.elementor-position-top .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-8f2fb4d .elementor-image-box-wrapper .elementor-image-box-img{width:35%;}.elementor-30 .elementor-element.elementor-element-8f2fb4d .elementor-image-box-img img{transition-duration:0.3s;}.elementor-30 .elementor-element.elementor-element-8f2fb4d .elementor-image-box-title{font-family:\"Kanit\", Sans-serif;font-size:20px;font-weight:500;text-transform:capitalize;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-8f2fb4d .elementor-image-box-description{font-family:\"Kanit\", Sans-serif;font-size:16px;font-weight:300;line-height:1.4em;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-87d2a28:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-30 .elementor-element.elementor-element-87d2a28 > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#ffffff;}.elementor-30 .elementor-element.elementor-element-87d2a28 > .elementor-element-populated, .elementor-30 .elementor-element.elementor-element-87d2a28 > .elementor-element-populated > .elementor-background-overlay, .elementor-30 .elementor-element.elementor-element-87d2a28 > .elementor-background-slideshow{border-radius:15px 15px 15px 70px;}.elementor-30 .elementor-element.elementor-element-87d2a28 > .elementor-element-populated{box-shadow:0px 0px 20px 0px rgba(0,0,0,0.05);transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;margin:3% 3% 3% 3%;--e-column-margin-right:3%;--e-column-margin-left:3%;padding:14% 14% 14% 14%;}.elementor-30 .elementor-element.elementor-element-87d2a28 > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-30 .elementor-element.elementor-element-868f4f1 .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-868f4f1.elementor-position-right .elementor-image-box-img{margin-left:15px;}.elementor-30 .elementor-element.elementor-element-868f4f1.elementor-position-left .elementor-image-box-img{margin-right:15px;}.elementor-30 .elementor-element.elementor-element-868f4f1.elementor-position-top .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-868f4f1 .elementor-image-box-wrapper .elementor-image-box-img{width:35%;}.elementor-30 .elementor-element.elementor-element-868f4f1 .elementor-image-box-img img{transition-duration:0.3s;}.elementor-30 .elementor-element.elementor-element-868f4f1 .elementor-image-box-title{font-family:\"Kanit\", Sans-serif;font-size:20px;font-weight:500;text-transform:capitalize;-webkit-text-stroke-color:#000;stroke:#000;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-868f4f1 .elementor-image-box-description{font-family:\"Kanit\", Sans-serif;font-size:16px;font-weight:300;line-height:1.4em;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-c5701e7:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-30 .elementor-element.elementor-element-c5701e7 > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#ffffff;}.elementor-30 .elementor-element.elementor-element-c5701e7 > .elementor-element-populated, .elementor-30 .elementor-element.elementor-element-c5701e7 > .elementor-element-populated > .elementor-background-overlay, .elementor-30 .elementor-element.elementor-element-c5701e7 > .elementor-background-slideshow{border-radius:15px 15px 15px 70px;}.elementor-30 .elementor-element.elementor-element-c5701e7 > .elementor-element-populated{box-shadow:0px 0px 20px 0px rgba(0,0,0,0.05);transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;margin:3% 3% 3% 3%;--e-column-margin-right:3%;--e-column-margin-left:3%;padding:14% 14% 14% 14%;}.elementor-30 .elementor-element.elementor-element-c5701e7 > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-30 .elementor-element.elementor-element-6f51f20 .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-6f51f20.elementor-position-right .elementor-image-box-img{margin-left:15px;}.elementor-30 .elementor-element.elementor-element-6f51f20.elementor-position-left .elementor-image-box-img{margin-right:15px;}.elementor-30 .elementor-element.elementor-element-6f51f20.elementor-position-top .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-6f51f20 .elementor-image-box-wrapper .elementor-image-box-img{width:35%;}.elementor-30 .elementor-element.elementor-element-6f51f20 .elementor-image-box-img img{transition-duration:0.3s;}.elementor-30 .elementor-element.elementor-element-6f51f20 .elementor-image-box-title{font-family:\"Kanit\", Sans-serif;font-size:20px;font-weight:500;text-transform:capitalize;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-6f51f20 .elementor-image-box-description{font-family:\"Kanit\", Sans-serif;font-size:16px;font-weight:300;line-height:1.4em;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-80cd985:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-30 .elementor-element.elementor-element-80cd985 > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#ffffff;}.elementor-30 .elementor-element.elementor-element-80cd985 > .elementor-element-populated, .elementor-30 .elementor-element.elementor-element-80cd985 > .elementor-element-populated > .elementor-background-overlay, .elementor-30 .elementor-element.elementor-element-80cd985 > .elementor-background-slideshow{border-radius:15px 15px 15px 70px;}.elementor-30 .elementor-element.elementor-element-80cd985 > .elementor-element-populated{box-shadow:0px 0px 20px 0px rgba(0,0,0,0.05);transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;margin:3% 3% 3% 3%;--e-column-margin-right:3%;--e-column-margin-left:3%;padding:14% 14% 14% 14%;}.elementor-30 .elementor-element.elementor-element-80cd985 > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-30 .elementor-element.elementor-element-795b152 .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-795b152.elementor-position-right .elementor-image-box-img{margin-left:15px;}.elementor-30 .elementor-element.elementor-element-795b152.elementor-position-left .elementor-image-box-img{margin-right:15px;}.elementor-30 .elementor-element.elementor-element-795b152.elementor-position-top .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-795b152 .elementor-image-box-wrapper .elementor-image-box-img{width:35%;}.elementor-30 .elementor-element.elementor-element-795b152 .elementor-image-box-img img{transition-duration:0.3s;}.elementor-30 .elementor-element.elementor-element-795b152 .elementor-image-box-title{font-family:\"Kanit\", Sans-serif;font-size:20px;font-weight:500;text-transform:capitalize;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-795b152 .elementor-image-box-description{font-family:\"Kanit\", Sans-serif;font-size:16px;font-weight:300;line-height:1.4em;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-0ba7d1e:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-30 .elementor-element.elementor-element-0ba7d1e > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#ffffff;}.elementor-30 .elementor-element.elementor-element-0ba7d1e > .elementor-element-populated, .elementor-30 .elementor-element.elementor-element-0ba7d1e > .elementor-element-populated > .elementor-background-overlay, .elementor-30 .elementor-element.elementor-element-0ba7d1e > .elementor-background-slideshow{border-radius:15px 15px 15px 70px;}.elementor-30 .elementor-element.elementor-element-0ba7d1e > .elementor-element-populated{box-shadow:0px 0px 20px 0px rgba(0,0,0,0.05);transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;margin:3% 3% 3% 3%;--e-column-margin-right:3%;--e-column-margin-left:3%;padding:14% 14% 14% 14%;}.elementor-30 .elementor-element.elementor-element-0ba7d1e > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-30 .elementor-element.elementor-element-7553020 .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-7553020.elementor-position-right .elementor-image-box-img{margin-left:15px;}.elementor-30 .elementor-element.elementor-element-7553020.elementor-position-left .elementor-image-box-img{margin-right:15px;}.elementor-30 .elementor-element.elementor-element-7553020.elementor-position-top .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-7553020 .elementor-image-box-wrapper .elementor-image-box-img{width:35%;}.elementor-30 .elementor-element.elementor-element-7553020 .elementor-image-box-img img{transition-duration:0.3s;}.elementor-30 .elementor-element.elementor-element-7553020 .elementor-image-box-title{font-family:\"Kanit\", Sans-serif;font-size:20px;font-weight:500;text-transform:capitalize;-webkit-text-stroke-color:#000;stroke:#000;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-7553020 .elementor-image-box-description{font-family:\"Kanit\", Sans-serif;font-size:16px;font-weight:300;line-height:1.4em;color:#3d4459;}.elementor-30 .elementor-element.elementor-element-aec8b9b > .elementor-widget-container{padding:0px 0px 0px 20px;}.elementor-30 .elementor-element.elementor-element-ed29b32{z-index:8;}.elementor-30 .elementor-element.elementor-element-ed29b32.elementor-column.jkit-sticky-element--enabled{position:sticky;height:fit-content;z-index:1;}.elementor-30 .elementor-element.elementor-element-ed29b32.elementor-column.jkit-sticky-element--enabled.sticky-pinned.jkit-sticky-element-on--down{top:120px;}.elementor-30 .elementor-element.elementor-element-ed29b32.elementor-column.jkit-sticky-element--enabled.sticky-pinned.jkit-sticky-element-on--both{top:120px;}#wpadminbar ~ .elementor-30 .elementor-element.elementor-element-ed29b32.elementor-column.jkit-sticky-element--enabled.sticky-pinned.jkit-sticky-element-on--down, #wpadminbar ~ * .elementor-30 .elementor-element.elementor-element-ed29b32.elementor-column.jkit-sticky-element--enabled.sticky-pinned.jkit-sticky-element-on--down{top:calc(120px + var(--wpadminbar-height, 0px));}#wpadminbar ~ .elementor-30 .elementor-element.elementor-element-ed29b32.elementor-column.jkit-sticky-element--enabled.sticky-pinned.jkit-sticky-element-on--both, #wpadminbar ~ * .elementor-30 .elementor-element.elementor-element-ed29b32.elementor-column.jkit-sticky-element--enabled.sticky-pinned.jkit-sticky-element-on--both{top:calc(120px + var(--wpadminbar-height, 0px));}.elementor-30 .elementor-element.elementor-element-18bce5a:not(.elementor-motion-effects-element-type-background), .elementor-30 .elementor-element.elementor-element-18bce5a > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#F4F4F4;}.elementor-30 .elementor-element.elementor-element-18bce5a{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;margin-top:0px;margin-bottom:30px;padding:26px 26px 26px 26px;z-index:0;}.elementor-30 .elementor-element.elementor-element-18bce5a > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-30 .elementor-element.elementor-element-cbd1327{z-index:1;}.elementor-30 .elementor-element.elementor-element-1b66a99 .elementor-heading-title{font-weight:500;color:#000000;}.elementor-widget-nav-menu .elementor-nav-menu .elementor-item{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );}.elementor-widget-nav-menu .elementor-nav-menu--main .elementor-item{color:var( --e-global-color-text );fill:var( --e-global-color-text );}.elementor-widget-nav-menu .elementor-nav-menu--main .elementor-item:hover,\n\t\t\t\t\t.elementor-widget-nav-menu .elementor-nav-menu--main .elementor-item.elementor-item-active,\n\t\t\t\t\t.elementor-widget-nav-menu .elementor-nav-menu--main .elementor-item.highlighted,\n\t\t\t\t\t.elementor-widget-nav-menu .elementor-nav-menu--main .elementor-item:focus{color:var( --e-global-color-accent );fill:var( --e-global-color-accent );}.elementor-widget-nav-menu .elementor-nav-menu--main:not(.e--pointer-framed) .elementor-item:before,\n\t\t\t\t\t.elementor-widget-nav-menu .elementor-nav-menu--main:not(.e--pointer-framed) .elementor-item:after{background-color:var( --e-global-color-accent );}.elementor-widget-nav-menu .e--pointer-framed .elementor-item:before,\n\t\t\t\t\t.elementor-widget-nav-menu .e--pointer-framed .elementor-item:after{border-color:var( --e-global-color-accent );}.elementor-widget-nav-menu{--e-nav-menu-divider-color:var( --e-global-color-text );}.elementor-widget-nav-menu .elementor-nav-menu--dropdown .elementor-item, .elementor-widget-nav-menu .elementor-nav-menu--dropdown  .elementor-sub-item{font-family:var( --e-global-typography-accent-font-family ), Sans-serif;font-weight:var( --e-global-typography-accent-font-weight );}.elementor-30 .elementor-element.elementor-element-5f9d431 .elementor-nav-menu .elementor-item{font-weight:400;}.elementor-30 .elementor-element.elementor-element-5f9d431 .elementor-nav-menu--main .elementor-item{color:#777777;fill:#777777;padding-top:12px;padding-bottom:12px;}.elementor-30 .elementor-element.elementor-element-5f9d431 .elementor-nav-menu--main .elementor-item.elementor-item-active{color:var( --e-global-color-accent );}.elementor-30 .elementor-element.elementor-element-5f9d431 > .elementor-widget-container{margin:-10px -10px 0px -20px;}body.elementor-page-30:not(.elementor-motion-effects-element-type-background), body.elementor-page-30 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#FFFFFF;}@media(max-width:1024px){.elementor-30 .elementor-element.elementor-element-23836b5 > .elementor-element-populated{margin:0px 0px 0px 0px;--e-column-margin-right:0px;--e-column-margin-left:0px;}.elementor-30 .elementor-element.elementor-element-08c5e95 .elementor-image-box-description{font-size:15px;}.elementor-30 .elementor-element.elementor-element-1c5968b .elementor-image-box-description{font-size:15px;}.elementor-30 .elementor-element.elementor-element-e2d5fd0 .elementor-image-box-description{font-size:15px;}.elementor-30 .elementor-element.elementor-element-aa25385 .elementor-image-box-description{font-size:15px;}.elementor-30 .elementor-element.elementor-element-8f2fb4d .elementor-image-box-description{font-size:15px;}.elementor-30 .elementor-element.elementor-element-868f4f1 .elementor-image-box-description{font-size:15px;}.elementor-30 .elementor-element.elementor-element-6f51f20 .elementor-image-box-description{font-size:15px;}.elementor-30 .elementor-element.elementor-element-795b152 .elementor-image-box-description{font-size:15px;}.elementor-30 .elementor-element.elementor-element-7553020 .elementor-image-box-description{font-size:15px;}}@media(min-width:768px){.elementor-30 .elementor-element.elementor-element-23836b5{width:74%;}.elementor-30 .elementor-element.elementor-element-ed29b32{width:26%;}}@media(max-width:1024px) and (min-width:768px){.elementor-30 .elementor-element.elementor-element-23836b5{width:65%;}.elementor-30 .elementor-element.elementor-element-ed29b32{width:35%;}}@media(max-width:767px){.elementor-30 .elementor-element.elementor-element-21794b7{margin-top:0px;margin-bottom:0px;}.elementor-30 .elementor-element.elementor-element-23836b5 > .elementor-element-populated{margin:0px 0px 0px 0px;--e-column-margin-right:0px;--e-column-margin-left:0px;}.elementor-30 .elementor-element.elementor-element-fa55c55 .elementor-heading-title{line-height:1.5em;}.elementor-30 .elementor-element.elementor-element-fa55c55 > .elementor-widget-container{padding:0px 0px 0px 20px;}.elementor-30 .elementor-element.elementor-element-6a1f43c > .elementor-widget-container{padding:0px 0px 0px 20px;}.elementor-30 .elementor-element.elementor-element-d8cdb3f .elementor-heading-title{font-size:30px;}.elementor-30 .elementor-element.elementor-element-d8cdb3f > .elementor-widget-container{padding:0px 0px 0px 20px;}.elementor-30 .elementor-element.elementor-element-d64213d > .elementor-widget-container{padding:0px 0px 0px 20px;}.elementor-30 .elementor-element.elementor-element-38dc8c8 > .elementor-element-populated{padding:10% 10% 10% 10%;}.elementor-30 .elementor-element.elementor-element-08c5e95 .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-08c5e95 .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-d7c01dd > .elementor-element-populated{padding:10% 10% 10% 10%;}.elementor-30 .elementor-element.elementor-element-1c5968b .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-1c5968b .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-950270f > .elementor-element-populated{padding:10% 10% 10% 10%;}.elementor-30 .elementor-element.elementor-element-e2d5fd0 .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-e2d5fd0 .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-7230a2a > .elementor-element-populated{padding:10% 10% 10% 10%;}.elementor-30 .elementor-element.elementor-element-aa25385 .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-aa25385 .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-4de4672 > .elementor-element-populated{padding:10% 10% 10% 10%;}.elementor-30 .elementor-element.elementor-element-8f2fb4d .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-8f2fb4d .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-87d2a28 > .elementor-element-populated{padding:10% 10% 10% 10%;}.elementor-30 .elementor-element.elementor-element-868f4f1 .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-868f4f1 .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-c5701e7 > .elementor-element-populated{padding:10% 10% 10% 10%;}.elementor-30 .elementor-element.elementor-element-6f51f20 .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-6f51f20 .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-80cd985 > .elementor-element-populated{padding:10% 10% 10% 10%;}.elementor-30 .elementor-element.elementor-element-795b152 .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-795b152 .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-0ba7d1e > .elementor-element-populated{padding:10% 10% 10% 10%;}.elementor-30 .elementor-element.elementor-element-7553020 .elementor-image-box-wrapper{text-align:center;}.elementor-30 .elementor-element.elementor-element-7553020 .elementor-image-box-img{margin-bottom:15px;}.elementor-30 .elementor-element.elementor-element-aec8b9b > .elementor-widget-container{padding:23px 23px 23px 23px;}}<\/style>\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"30\" class=\"elementor elementor-30\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21794b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21794b7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-23836b5\" data-id=\"23836b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72209f1 elementor-widget elementor-widget-image\" data-id=\"72209f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/www.skyfrog.net\/home\/wp-content\/uploads\/2023\/05\/5.jpg\" class=\"attachment-full size-full wp-image-557\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa55c55 elementor-widget elementor-widget-heading\" data-id=\"fa55c55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a Cloud \u0e02\u0e2d\u0e07 SKYFROG \u0e0a\u0e48\u0e27\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a1f43c elementor-widget elementor-widget-text-editor\" data-id=\"6a1f43c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a Cloud \u0e02\u0e2d\u0e07 SKYFROG \u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19 \u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 Cloud Computing \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e25\u0e07\u0e17\u0e38\u0e19\u0e14\u0e49\u0e32\u0e19 Server \u0e41\u0e25\u0e30 Infrastructure \u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e2d\u0e07 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8cdb3f elementor-widget elementor-widget-heading\" data-id=\"d8cdb3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e14\u0e48\u0e19\u0e02\u0e2d\u0e07 SKYFROG Web Application<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d64213d elementor-widget elementor-widget-text-editor\" data-id=\"d64213d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SKYFROG Web Application \u0e40\u0e1b\u0e47\u0e19\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1a\u0e19 Web Browser \u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a Cloud \u0e02\u0e2d\u0e07 SKYFROG \u0e21\u0e35\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e14\u0e48\u0e19\u0e46 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f0ae6da elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f0ae6da\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-38dc8c8\" data-id=\"38dc8c8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08c5e95 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"08c5e95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.skyfrog.net\/home\/wp-content\/uploads\/2024\/04\/real-time-strategy.png\" class=\"attachment-full size-full wp-image-2885\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h2 class=\"elementor-image-box-title\">\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e25\u0e44\u0e17\u0e21\u0e4c<\/h2><p class=\"elementor-image-box-description\"><span style=\"font-family: Kanit, sans-serif;font-size: 16px;font-style: normal\">\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e44\u0e14\u0e49\u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e25\u0e44\u0e17\u0e21\u0e4c<\/span><\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d7c01dd\" data-id=\"d7c01dd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c5968b elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1c5968b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.skyfrog.net\/home\/wp-content\/uploads\/2024\/04\/data-storage.png\" class=\"attachment-full size-full wp-image-2884\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25<\/h3><p class=\"elementor-image-box-description\"><span style=\"font-family: Kanit, sans-serif;font-size: 16px;font-style: normal\">\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e0a\u0e48\u0e19 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27 \u0e17\u0e34\u0e28\u0e17\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e27\u0e25\u0e32<\/span><\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-950270f\" data-id=\"950270f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2d5fd0 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"e2d5fd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.skyfrog.net\/home\/wp-content\/uploads\/2024\/04\/new-message.png\" class=\"attachment-full size-full wp-image-2883\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0e01\u0e32\u0e23\u0e41\u0e08\u0e49\u0e07\u0e40\u0e15\u0e37\u0e2d\u0e19<\/h3><p class=\"elementor-image-box-description\"><span style=\"font-family: Kanit, sans-serif;font-size: 16px;font-style: normal\">\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e08\u0e49\u0e07\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e01\u0e34\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e40\u0e0a\u0e48\u0e19 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e2d\u0e2d\u0e01\u0e19\u0e2d\u0e01\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e40\u0e01\u0e34\u0e19\u0e01\u0e33\u0e2b\u0e19\u0e14<\/span><\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f13d7cb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f13d7cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7230a2a\" data-id=\"7230a2a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa25385 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"aa25385\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.skyfrog.net\/home\/wp-content\/uploads\/2024\/04\/timeline.png\" class=\"attachment-full size-full wp-image-2891\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e25\u0e33\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19<\/h3><p class=\"elementor-image-box-description\">\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e25\u0e33\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4de4672\" data-id=\"4de4672\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f2fb4d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8f2fb4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.skyfrog.net\/home\/wp-content\/uploads\/2024\/04\/boxes.png\" class=\"attachment-full size-full wp-image-2890\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e30 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e25\u0e32\u0e22\u0e40\u0e0b\u0e47\u0e19<\/h3><p class=\"elementor-image-box-description\">\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e30 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e25\u0e32\u0e22\u0e40\u0e0b\u0e47\u0e19<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-87d2a28\" data-id=\"87d2a28\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-868f4f1 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"868f4f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.skyfrog.net\/home\/wp-content\/uploads\/2024\/04\/map.png\" class=\"attachment-full size-full wp-image-2889\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 Points of Interest (POI)<\/h3><p class=\"elementor-image-box-description\">\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 Points of Interest (POI) \u0e40\u0e0a\u0e48\u0e19 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e38\u0e14\u0e2a\u0e19\u0e43\u0e08\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2b\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2f\u0e25\u0e2f<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a9a2afa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a9a2afa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c5701e7\" data-id=\"c5701e7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f51f20 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"6f51f20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.skyfrog.net\/home\/wp-content\/uploads\/2024\/04\/mail.png\" class=\"attachment-full size-full wp-image-2888\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e08\u0e49\u0e07\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e30 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e4c\u0e41\u0e1a\u0e1a Real-time<\/h3><p class=\"elementor-image-box-description\">\u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e08\u0e49\u0e07\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e30 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e4c\u0e41\u0e1a\u0e1a Real-time \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e35\u0e48\u0e43\u0e01\u0e25\u0e49\u0e21\u0e32\u0e16\u0e36\u0e07\u0e08\u0e38\u0e14\u0e2b\u0e21\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-80cd985\" data-id=\"80cd985\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-795b152 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"795b152\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.skyfrog.net\/home\/wp-content\/uploads\/2024\/04\/battery.png\" class=\"attachment-full size-full wp-image-2886\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e40\u0e15\u0e37\u0e2d\u0e19<\/h3><p class=\"elementor-image-box-description\">\u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e40\u0e15\u0e37\u0e2d\u0e19 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e19\u0e2d\u0e01\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e40\u0e01\u0e34\u0e19\u0e01\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e43\u0e01\u0e25\u0e49\u0e08\u0e30\u0e2b\u0e21\u0e14<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0ba7d1e\" data-id=\"0ba7d1e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7553020 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7553020\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.skyfrog.net\/home\/wp-content\/uploads\/2024\/04\/report.png\" class=\"attachment-full size-full wp-image-2887\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19<\/h3><p class=\"elementor-image-box-description\">\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19 (Reports) \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e30\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e04\u0e48\u0e32\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e02\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e2d\u0e35\u0e01\u0e01\u0e27\u0e48\u0e32 30 \u0e0a\u0e19\u0e34\u0e14<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-aec8b9b elementor-widget elementor-widget-text-editor\" data-id=\"aec8b9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a Cloud \u0e02\u0e2d\u0e07 SKYFROG \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ed29b32 jkit-sticky-element--enabled jkit-sticky-element-on--down jkit-sticky-position--sticky\" data-id=\"ed29b32\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;jkit_sticky_device&quot;:[&quot;desktop&quot;],&quot;jkit_sticky_top_position&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:120,&quot;sizes&quot;:[]}}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-18bce5a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18bce5a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-cbd1327\" data-id=\"cbd1327\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b66a99 elementor-widget elementor-widget-heading\" data-id=\"1b66a99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f9d431 elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"5f9d431\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-5f9d431\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-412\"><a href=\"https:\/\/www.skyfrog.net\/home\/en\/sky-frog-who\/\" class=\"elementor-item\"><i class=\"fa fa-chevron-circle-right\" aria-hidden=\"true\"><\/i>\u00a0Sky Frog \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-414\"><a href=\"https:\/\/www.skyfrog.net\/home\/en\/features\/\" class=\"elementor-item\"><i class=\"fa fa-chevron-circle-right\" aria-hidden=\"true\"><\/i>\u00a0\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e25\u0e31\u0e01<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-622\"><a href=\"https:\/\/www.skyfrog.net\/home\/en\/plan\/\" class=\"elementor-item\"><i class=\"fa fa-chevron-circle-right\" aria-hidden=\"true\"><\/i>\u00a0\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e23\u0e16\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-411\"><a href=\"https:\/\/www.skyfrog.net\/home\/en\/proof-of-delivery\/\" class=\"elementor-item\"><i class=\"fa fa-chevron-circle-right\" aria-hidden=\"true\"><\/i>\u00a0Proof of Delivery<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-413\"><a href=\"https:\/\/www.skyfrog.net\/home\/en\/gps-track\/\" class=\"elementor-item\"><i class=\"fa fa-chevron-circle-right\" aria-hidden=\"true\"><\/i>\u00a0\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 GPS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-415\"><a href=\"https:\/\/www.skyfrog.net\/home\/en\/cloud\/\" class=\"elementor-item\"><i class=\"fa fa-chevron-circle-right\" aria-hidden=\"true\"><\/i>\u00a0\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a Cloud<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-621\"><a href=\"https:\/\/www.skyfrog.net\/home\/en\/dashboards\/\" class=\"elementor-item\"><i class=\"fa fa-chevron-circle-right\" aria-hidden=\"true\"><\/i>\u00a0\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e49\u0e27\u0e22 Dashboards<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-5f9d431\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-412\"><a href=\"https:\/\/www.skyfrog.net\/home\/en\/sky-frog-who\/\" class=\"elementor-item\" tabindex=\"-1\"><i class=\"fa fa-chevron-circle-right\" aria-hidden=\"true\"><\/i>\u00a0Sky Frog \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-414\"><a href=\"https:\/\/www.skyfrog.net\/home\/en\/features\/\" class=\"elementor-item\" tabindex=\"-1\"><i class=\"fa fa-chevron-circle-right\" aria-hidden=\"true\"><\/i>\u00a0\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e25\u0e31\u0e01<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-622\"><a href=\"https:\/\/www.skyfrog.net\/home\/en\/plan\/\" class=\"elementor-item\" tabindex=\"-1\"><i class=\"fa fa-chevron-circle-right\" aria-hidden=\"true\"><\/i>\u00a0\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e23\u0e16\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-411\"><a href=\"https:\/\/www.skyfrog.net\/home\/en\/proof-of-delivery\/\" class=\"elementor-item\" tabindex=\"-1\"><i class=\"fa fa-chevron-circle-right\" aria-hidden=\"true\"><\/i>\u00a0Proof of Delivery<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-413\"><a href=\"https:\/\/www.skyfrog.net\/home\/en\/gps-track\/\" class=\"elementor-item\" tabindex=\"-1\"><i class=\"fa fa-chevron-circle-right\" aria-hidden=\"true\"><\/i>\u00a0\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 GPS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-415\"><a href=\"https:\/\/www.skyfrog.net\/home\/en\/cloud\/\" class=\"elementor-item\" tabindex=\"-1\"><i class=\"fa fa-chevron-circle-right\" aria-hidden=\"true\"><\/i>\u00a0\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a Cloud<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-621\"><a href=\"https:\/\/www.skyfrog.net\/home\/en\/dashboards\/\" class=\"elementor-item\" tabindex=\"-1\"><i class=\"fa fa-chevron-circle-right\" aria-hidden=\"true\"><\/i>\u00a0\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e49\u0e27\u0e22 Dashboards<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a Cloud \u0e02\u0e2d\u0e07 SKYFROG \u0e0a\u0e48\u0e27\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a Cloud \u0e02\u0e2d\u0e07 SKYFROG \u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19 \u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 Cloud Computing \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e25\u0e07\u0e17\u0e38\u0e19\u0e14\u0e49\u0e32\u0e19 Server \u0e41\u0e25\u0e30 Infrastructure \u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e2d\u0e07 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19 \u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e14\u0e48\u0e19\u0e02\u0e2d\u0e07 SKYFROG Web Application SKYFROG Web Application \u0e40\u0e1b\u0e47\u0e19\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1a\u0e19 Web Browser \u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a Cloud \u0e02\u0e2d\u0e07 SKYFROG \u0e21\u0e35\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e14\u0e48\u0e19\u0e46 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e25\u0e44\u0e17\u0e21\u0e4c \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e44\u0e14\u0e49\u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e25\u0e44\u0e17\u0e21\u0e4c \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e0a\u0e48\u0e19 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27 \u0e17\u0e34\u0e28\u0e17\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e27\u0e25\u0e32 \u0e01\u0e32\u0e23\u0e41\u0e08\u0e49\u0e07\u0e40\u0e15\u0e37\u0e2d\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e08\u0e49\u0e07\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e01\u0e34\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e40\u0e0a\u0e48\u0e19 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e2d\u0e2d\u0e01\u0e19\u0e2d\u0e01\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e40\u0e01\u0e34\u0e19\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e25\u0e33\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e25\u0e33\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-30","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/www.skyfrog.net\/home\/en\/wp-json\/wp\/v2\/pages\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.skyfrog.net\/home\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.skyfrog.net\/home\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.skyfrog.net\/home\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.skyfrog.net\/home\/en\/wp-json\/wp\/v2\/comments?post=30"}],"version-history":[{"count":19,"href":"https:\/\/www.skyfrog.net\/home\/en\/wp-json\/wp\/v2\/pages\/30\/revisions"}],"predecessor-version":[{"id":2897,"href":"https:\/\/www.skyfrog.net\/home\/en\/wp-json\/wp\/v2\/pages\/30\/revisions\/2897"}],"wp:attachment":[{"href":"https:\/\/www.skyfrog.net\/home\/en\/wp-json\/wp\/v2\/media?parent=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}